{"id":96,"date":"2026-08-27T20:23:38","date_gmt":"2026-08-27T20:23:38","guid":{"rendered":"https:\/\/taxilamangacartagena.es\/?page_id=96"},"modified":"2026-08-27T22:03:29","modified_gmt":"2026-08-27T22:03:29","slug":"taxi-excursiones-cartagena","status":"publish","type":"page","link":"https:\/\/taxilamangacartagena.es\/index.php\/taxi-excursiones-cartagena\/","title":{"rendered":"Excursiones y Traslados"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"96\" class=\"elementor elementor-96\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fea9850 e-con e-atomic-element e-flexbox-base e-e59f42b \" data-id=\"fea9850\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"fea9850\">\n    \t\t<div class=\"elementor-element elementor-element-f8646b2 elementor-widget elementor-widget-html\" data-id=\"f8646b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<link rel=\"preconnect\" href=\"https:\/\/fonts.googleapis.com\">\r\n<link rel=\"preconnect\" href=\"https:\/\/fonts.gstatic.com\" crossorigin>\r\n<link href=\"https:\/\/fonts.googleapis.com\/css2?family=Manrope:wght@400;500;600;700;800&display=swap\" rel=\"stylesheet\">\r\n\r\n<style>\r\n\r\n\/* =========================================================\r\n   EUROTAXI CARTAGENA\r\n   EXCURSIONES Y TRASLADOS\r\n   ========================================================= *\/\r\n\r\n.etxtrip-page{\r\n    --green:#C6F43D;\r\n    --green-dark:#A9DB20;\r\n    --black:#0D100D;\r\n    --black-soft:#171C17;\r\n    --text:#505850;\r\n    --soft:#F5F7F2;\r\n    --border:#E1E6DD;\r\n    --white:#FFFFFF;\r\n\r\n    width:100%;\r\n    max-width:100%;\r\n    overflow:hidden;\r\n\r\n    background:#fff;\r\n    color:var(--black);\r\n\r\n    font-family:\"Manrope\",Arial,sans-serif;\r\n}\r\n\r\n.etxtrip-page *,\r\n.etxtrip-page *::before,\r\n.etxtrip-page *::after{\r\n    box-sizing:border-box;\r\n}\r\n\r\n.etxtrip-page img{\r\n    display:block;\r\n    max-width:100%;\r\n}\r\n\r\n.etxtrip-page a{\r\n    text-decoration:none;\r\n}\r\n\r\n.etxtrip-wrap{\r\n    width:min(1180px,calc(100% - 48px));\r\n    margin:0 auto;\r\n}\r\n\r\n.etxtrip-section{\r\n    padding:105px 0;\r\n}\r\n\r\n.etxtrip-eyebrow{\r\n    display:inline-flex;\r\n    align-items:center;\r\n    gap:9px;\r\n\r\n    margin-bottom:18px;\r\n\r\n    color:#739400;\r\n\r\n    font-size:12px;\r\n    font-weight:800;\r\n    letter-spacing:1.6px;\r\n    text-transform:uppercase;\r\n}\r\n\r\n.etxtrip-eyebrow::before{\r\n    content:\"\";\r\n\r\n    width:27px;\r\n    height:3px;\r\n\r\n    background:var(--green);\r\n\r\n    border-radius:99px;\r\n}\r\n\r\n.etxtrip-title{\r\n    margin:0;\r\n\r\n    font-size:clamp(37px,4.5vw,61px);\r\n    line-height:1.04;\r\n\r\n    font-weight:800;\r\n    letter-spacing:-2.4px;\r\n}\r\n\r\n.etxtrip-text{\r\n    margin:22px 0 0;\r\n\r\n    color:var(--text);\r\n\r\n    font-size:16px;\r\n    line-height:1.76;\r\n}\r\n\r\n\r\n\/* =========================================================\r\n   BOTONES\r\n   ========================================================= *\/\r\n\r\n.etxtrip-btns{\r\n    display:flex;\r\n    flex-wrap:wrap;\r\n    gap:12px;\r\n\r\n    margin-top:32px;\r\n}\r\n\r\n.etxtrip-btn{\r\n    min-height:54px;\r\n\r\n    display:inline-flex;\r\n    align-items:center;\r\n    justify-content:center;\r\n    gap:9px;\r\n\r\n    padding:0 24px;\r\n\r\n    border-radius:12px;\r\n\r\n    font-size:13px;\r\n    font-weight:800;\r\n\r\n    transition:\r\n        transform .25s ease,\r\n        background .25s ease,\r\n        border-color .25s ease,\r\n        color .25s ease;\r\n}\r\n\r\n.etxtrip-btn:hover{\r\n    transform:translateY(-2px);\r\n}\r\n\r\n.etxtrip-btn-green{\r\n    background:var(--green);\r\n    border:1px solid var(--green);\r\n\r\n    color:#111 !important;\r\n}\r\n\r\n.etxtrip-btn-green:hover,\r\n.etxtrip-btn-green:focus{\r\n    background:var(--green-dark);\r\n    border-color:var(--green-dark);\r\n\r\n    color:#fff !important;\r\n}\r\n\r\n.etxtrip-btn-dark{\r\n    background:var(--black);\r\n    border:1px solid var(--black);\r\n\r\n    color:#fff !important;\r\n}\r\n\r\n.etxtrip-btn-dark:hover,\r\n.etxtrip-btn-dark:focus{\r\n    background:var(--green);\r\n    border-color:var(--green);\r\n\r\n    color:#111 !important;\r\n}\r\n\r\n.etxtrip-btn-light{\r\n    background:rgba(255,255,255,.08);\r\n    border:1px solid rgba(255,255,255,.48);\r\n\r\n    color:#fff !important;\r\n}\r\n\r\n.etxtrip-btn-light:hover,\r\n.etxtrip-btn-light:focus{\r\n    background:rgba(255,255,255,.17);\r\n    border-color:#fff;\r\n\r\n    color:#fff !important;\r\n}\r\n\r\n\r\n\/* =========================================================\r\n   HERO\r\n   ========================================================= *\/\r\n\r\n.etxtrip-hero{\r\n    position:relative;\r\n\r\n    min-height:720px;\r\n\r\n    display:flex;\r\n    align-items:center;\r\n\r\n    isolation:isolate;\r\n\r\n    background:#111;\r\n}\r\n\r\n.etxtrip-hero-bg{\r\n    position:absolute;\r\n    inset:0;\r\n\r\n    z-index:-3;\r\n}\r\n\r\n.etxtrip-hero-bg img{\r\n    width:100%;\r\n    height:100%;\r\n\r\n    object-fit:cover;\r\n    object-position:center;\r\n}\r\n\r\n.etxtrip-hero::before{\r\n    content:\"\";\r\n\r\n    position:absolute;\r\n    inset:0;\r\n\r\n    z-index:-2;\r\n\r\n    background:\r\n        linear-gradient(\r\n            90deg,\r\n            rgba(6,8,6,.94) 0%,\r\n            rgba(6,8,6,.82) 40%,\r\n            rgba(6,8,6,.43) 70%,\r\n            rgba(6,8,6,.15) 100%\r\n        );\r\n}\r\n\r\n.etxtrip-hero-content{\r\n    max-width:800px;\r\n\r\n    padding:105px 0;\r\n}\r\n\r\n.etxtrip-hero-label{\r\n    display:inline-flex;\r\n    align-items:center;\r\n    gap:9px;\r\n\r\n    margin-bottom:24px;\r\n\r\n    padding:9px 14px;\r\n\r\n    border:1px solid rgba(255,255,255,.22);\r\n    border-radius:999px;\r\n\r\n    background:rgba(0,0,0,.29);\r\n\r\n    color:#fff;\r\n\r\n    font-size:11px;\r\n    font-weight:800;\r\n    letter-spacing:1.45px;\r\n    text-transform:uppercase;\r\n}\r\n\r\n.etxtrip-hero-label::before{\r\n    content:\"\";\r\n\r\n    width:8px;\r\n    height:8px;\r\n\r\n    border-radius:50%;\r\n\r\n    background:var(--green);\r\n\r\n    box-shadow:\r\n        0 0 0 5px\r\n        rgba(198,244,61,.14);\r\n}\r\n\r\n.etxtrip-hero h1{\r\n    max-width:820px;\r\n\r\n    margin:0;\r\n\r\n    color:#fff;\r\n\r\n    font-size:clamp(48px,6vw,79px);\r\n    line-height:.99;\r\n\r\n    font-weight:800;\r\n    letter-spacing:-3.7px;\r\n}\r\n\r\n.etxtrip-hero h1 strong{\r\n    color:var(--green);\r\n}\r\n\r\n.etxtrip-hero-text{\r\n    max-width:680px;\r\n\r\n    margin:25px 0 0;\r\n\r\n    color:rgba(255,255,255,.83);\r\n\r\n    font-size:17px;\r\n    line-height:1.72;\r\n}\r\n\r\n.etxtrip-points{\r\n    display:flex;\r\n    flex-wrap:wrap;\r\n\r\n    gap:14px 24px;\r\n\r\n    margin-top:35px;\r\n}\r\n\r\n.etxtrip-point{\r\n    display:flex;\r\n    align-items:center;\r\n    gap:8px;\r\n\r\n    color:#fff;\r\n\r\n    font-size:12px;\r\n    font-weight:700;\r\n}\r\n\r\n.etxtrip-point span{\r\n    width:22px;\r\n    height:22px;\r\n\r\n    flex:0 0 22px;\r\n\r\n    display:flex;\r\n    align-items:center;\r\n    justify-content:center;\r\n\r\n    border-radius:50%;\r\n\r\n    background:var(--green);\r\n\r\n    color:#111;\r\n\r\n    font-size:11px;\r\n}\r\n\r\n\r\n\/* =========================================================\r\n   INTRO\r\n   ========================================================= *\/\r\n\r\n.etxtrip-intro{\r\n    background:#fff;\r\n}\r\n\r\n.etxtrip-intro-grid{\r\n    display:grid;\r\n    grid-template-columns:1fr 1fr;\r\n\r\n    gap:82px;\r\n\r\n    align-items:center;\r\n}\r\n\r\n.etxtrip-intro-photo{\r\n    position:relative;\r\n}\r\n\r\n.etxtrip-intro-photo img{\r\n    width:100%;\r\n    height:620px;\r\n\r\n    object-fit:cover;\r\n\r\n    border-radius:25px;\r\n}\r\n\r\n.etxtrip-floating{\r\n    position:absolute;\r\n\r\n    right:-24px;\r\n    bottom:28px;\r\n\r\n    width:220px;\r\n\r\n    padding:22px;\r\n\r\n    border-radius:18px;\r\n\r\n    background:var(--green);\r\n\r\n    box-shadow:\r\n        0 18px 48px\r\n        rgba(0,0,0,.15);\r\n}\r\n\r\n.etxtrip-floating strong{\r\n    display:block;\r\n\r\n    font-size:17px;\r\n    line-height:1.25;\r\n}\r\n\r\n.etxtrip-floating span{\r\n    display:block;\r\n\r\n    margin-top:7px;\r\n\r\n    color:rgba(17,17,17,.65);\r\n\r\n    font-size:11px;\r\n    line-height:1.5;\r\n}\r\n\r\n\r\n\/* =========================================================\r\n   BENEFICIOS\r\n   ========================================================= *\/\r\n\r\n.etxtrip-benefits{\r\n    display:grid;\r\n    gap:14px;\r\n\r\n    margin-top:30px;\r\n}\r\n\r\n.etxtrip-benefit{\r\n    display:flex;\r\n    align-items:flex-start;\r\n    gap:13px;\r\n\r\n    padding-bottom:14px;\r\n\r\n    border-bottom:1px solid var(--border);\r\n}\r\n\r\n.etxtrip-benefit:last-child{\r\n    border-bottom:0;\r\n}\r\n\r\n.etxtrip-check{\r\n    width:27px;\r\n    height:27px;\r\n\r\n    flex:0 0 27px;\r\n\r\n    display:flex;\r\n    align-items:center;\r\n    justify-content:center;\r\n\r\n    border-radius:8px;\r\n\r\n    background:var(--green);\r\n\r\n    color:#111;\r\n\r\n    font-size:11px;\r\n    font-weight:900;\r\n}\r\n\r\n.etxtrip-benefit strong{\r\n    display:block;\r\n\r\n    margin-top:2px;\r\n\r\n    font-size:14px;\r\n}\r\n\r\n.etxtrip-benefit p{\r\n    margin:4px 0 0;\r\n\r\n    color:#687168;\r\n\r\n    font-size:12px;\r\n    line-height:1.55;\r\n}\r\n\r\n\r\n\/* =========================================================\r\n   TIPOS DE VIAJE\r\n   ========================================================= *\/\r\n\r\n.etxtrip-types{\r\n    background:var(--soft);\r\n}\r\n\r\n.etxtrip-types-head{\r\n    max-width:750px;\r\n\r\n    margin-bottom:50px;\r\n}\r\n\r\n.etxtrip-types-grid{\r\n    display:grid;\r\n    grid-template-columns:repeat(3,1fr);\r\n\r\n    gap:18px;\r\n}\r\n\r\n.etxtrip-type-card{\r\n    position:relative;\r\n\r\n    min-height:390px;\r\n\r\n    overflow:hidden;\r\n\r\n    border-radius:21px;\r\n\r\n    isolation:isolate;\r\n\r\n    background:#111;\r\n}\r\n\r\n.etxtrip-type-card img{\r\n    position:absolute;\r\n    inset:0;\r\n\r\n    z-index:-2;\r\n\r\n    width:100%;\r\n    height:100%;\r\n\r\n    object-fit:cover;\r\n\r\n    transition:transform .55s ease;\r\n}\r\n\r\n.etxtrip-type-card::before{\r\n    content:\"\";\r\n\r\n    position:absolute;\r\n    inset:0;\r\n\r\n    z-index:-1;\r\n\r\n    background:\r\n        linear-gradient(\r\n            to top,\r\n            rgba(5,7,5,.94),\r\n            rgba(5,7,5,.45) 50%,\r\n            rgba(5,7,5,.08)\r\n        );\r\n}\r\n\r\n.etxtrip-type-card:hover img{\r\n    transform:scale(1.045);\r\n}\r\n\r\n.etxtrip-type-content{\r\n    position:absolute;\r\n\r\n    left:0;\r\n    right:0;\r\n    bottom:0;\r\n\r\n    padding:28px;\r\n\r\n    color:#fff;\r\n}\r\n\r\n.etxtrip-type-icon{\r\n    width:39px;\r\n    height:39px;\r\n\r\n    display:flex;\r\n    align-items:center;\r\n    justify-content:center;\r\n\r\n    margin-bottom:17px;\r\n\r\n    border-radius:11px;\r\n\r\n    background:var(--green);\r\n\r\n    font-size:18px;\r\n}\r\n\r\n.etxtrip-type-card h3{\r\n    margin:0;\r\n\r\n    color:#fff;\r\n\r\n    font-size:22px;\r\n}\r\n\r\n.etxtrip-type-card p{\r\n    margin:9px 0 0;\r\n\r\n    color:rgba(255,255,255,.76);\r\n\r\n    font-size:12.5px;\r\n    line-height:1.65;\r\n}\r\n\r\n\r\n\/* =========================================================\r\n   PLAYAS\r\n   ========================================================= *\/\r\n\r\n.etxtrip-beach{\r\n    background:var(--black);\r\n\r\n    color:#fff;\r\n}\r\n\r\n.etxtrip-beach-grid{\r\n    display:grid;\r\n    grid-template-columns:.92fr 1.08fr;\r\n\r\n    gap:80px;\r\n\r\n    align-items:center;\r\n}\r\n\r\n.etxtrip-beach .etxtrip-eyebrow{\r\n    color:var(--green);\r\n}\r\n\r\n.etxtrip-beach .etxtrip-title{\r\n    color:#fff;\r\n}\r\n\r\n.etxtrip-beach .etxtrip-text{\r\n    color:rgba(255,255,255,.72);\r\n}\r\n\r\n.etxtrip-beach-images{\r\n    display:grid;\r\n    grid-template-columns:1.08fr .92fr;\r\n\r\n    gap:14px;\r\n}\r\n\r\n.etxtrip-beach-images img{\r\n    width:100%;\r\n\r\n    object-fit:cover;\r\n\r\n    border-radius:18px;\r\n}\r\n\r\n.etxtrip-beach-images img:first-child{\r\n    height:540px;\r\n}\r\n\r\n.etxtrip-beach-images img:last-child{\r\n    height:390px;\r\n\r\n    margin-top:72px;\r\n}\r\n\r\n.etxtrip-beach a:hover,\r\n.etxtrip-beach a:focus{\r\n    color:#fff !important;\r\n}\r\n\r\n\r\n\/* =========================================================\r\n   GOLF\r\n   ========================================================= *\/\r\n\r\n.etxtrip-golf{\r\n    background:#fff;\r\n}\r\n\r\n.etxtrip-golf-grid{\r\n    display:grid;\r\n    grid-template-columns:1.05fr .95fr;\r\n\r\n    gap:78px;\r\n\r\n    align-items:center;\r\n}\r\n\r\n.etxtrip-golf-photo img{\r\n    width:100%;\r\n    height:590px;\r\n\r\n    object-fit:cover;\r\n\r\n    border-radius:24px;\r\n}\r\n\r\n.etxtrip-tags{\r\n    display:flex;\r\n    flex-wrap:wrap;\r\n\r\n    gap:9px;\r\n\r\n    margin-top:28px;\r\n}\r\n\r\n.etxtrip-tag{\r\n    padding:9px 13px;\r\n\r\n    border:1px solid var(--border);\r\n    border-radius:999px;\r\n\r\n    background:#fff;\r\n\r\n    color:#343A34;\r\n\r\n    font-size:11px;\r\n    font-weight:700;\r\n}\r\n\r\n\r\n\/* =========================================================\r\n   HOTELES\r\n   ========================================================= *\/\r\n\r\n.etxtrip-hotels{\r\n    background:var(--soft);\r\n}\r\n\r\n.etxtrip-hotels-grid{\r\n    display:grid;\r\n    grid-template-columns:.9fr 1.1fr;\r\n\r\n    gap:78px;\r\n\r\n    align-items:center;\r\n}\r\n\r\n.etxtrip-hotels-photo img{\r\n    width:100%;\r\n    height:580px;\r\n\r\n    object-fit:cover;\r\n\r\n    border-radius:24px;\r\n}\r\n\r\n\r\n\/* =========================================================\r\n   VIAJES POR CARRETERA\r\n   ========================================================= *\/\r\n\r\n.etxtrip-road{\r\n    position:relative;\r\n\r\n    min-height:620px;\r\n\r\n    display:flex;\r\n    align-items:center;\r\n\r\n    isolation:isolate;\r\n\r\n    background:#111;\r\n}\r\n\r\n.etxtrip-road-bg{\r\n    position:absolute;\r\n    inset:0;\r\n\r\n    z-index:-3;\r\n}\r\n\r\n.etxtrip-road-bg img{\r\n    width:100%;\r\n    height:100%;\r\n\r\n    object-fit:cover;\r\n}\r\n\r\n.etxtrip-road::before{\r\n    content:\"\";\r\n\r\n    position:absolute;\r\n    inset:0;\r\n\r\n    z-index:-2;\r\n\r\n    background:\r\n        linear-gradient(\r\n            90deg,\r\n            rgba(5,7,5,.94),\r\n            rgba(5,7,5,.80) 50%,\r\n            rgba(5,7,5,.25)\r\n        );\r\n}\r\n\r\n.etxtrip-road-content{\r\n    max-width:680px;\r\n\r\n    padding:95px 0;\r\n}\r\n\r\n.etxtrip-road .etxtrip-eyebrow{\r\n    color:var(--green);\r\n}\r\n\r\n.etxtrip-road .etxtrip-title{\r\n    color:#fff;\r\n}\r\n\r\n.etxtrip-road .etxtrip-text{\r\n    color:rgba(255,255,255,.75);\r\n}\r\n\r\n.etxtrip-road a:hover,\r\n.etxtrip-road a:focus{\r\n    color:#fff !important;\r\n}\r\n\r\n\r\n\/* =========================================================\r\n   C\u00d3MO RESERVAR\r\n   ========================================================= *\/\r\n\r\n.etxtrip-process{\r\n    background:#fff;\r\n}\r\n\r\n.etxtrip-process-head{\r\n    max-width:720px;\r\n\r\n    margin-bottom:50px;\r\n}\r\n\r\n.etxtrip-process-grid{\r\n    display:grid;\r\n    grid-template-columns:repeat(3,1fr);\r\n\r\n    gap:18px;\r\n}\r\n\r\n.etxtrip-process-card{\r\n    padding:32px;\r\n\r\n    border:1px solid var(--border);\r\n    border-radius:19px;\r\n\r\n    background:var(--soft);\r\n}\r\n\r\n.etxtrip-process-num{\r\n    width:41px;\r\n    height:41px;\r\n\r\n    display:flex;\r\n    align-items:center;\r\n    justify-content:center;\r\n\r\n    margin-bottom:21px;\r\n\r\n    border-radius:11px;\r\n\r\n    background:var(--green);\r\n\r\n    color:#111;\r\n\r\n    font-size:12px;\r\n    font-weight:800;\r\n}\r\n\r\n.etxtrip-process-card h3{\r\n    margin:0;\r\n\r\n    font-size:19px;\r\n}\r\n\r\n.etxtrip-process-card p{\r\n    margin:10px 0 0;\r\n\r\n    color:var(--text);\r\n\r\n    font-size:13px;\r\n    line-height:1.65;\r\n}\r\n\r\n\r\n\/* =========================================================\r\n   SEO\r\n   ========================================================= *\/\r\n\r\n.etxtrip-seo{\r\n    padding:80px 0;\r\n\r\n    background:var(--soft);\r\n}\r\n\r\n.etxtrip-seo-inner{\r\n    max-width:910px;\r\n\r\n    margin:0 auto;\r\n}\r\n\r\n.etxtrip-seo h2{\r\n    margin:0;\r\n\r\n    font-size:clamp(30px,3.6vw,47px);\r\n    line-height:1.08;\r\n\r\n    letter-spacing:-1.7px;\r\n}\r\n\r\n.etxtrip-seo p{\r\n    margin:20px 0 0;\r\n\r\n    color:var(--text);\r\n\r\n    font-size:15px;\r\n    line-height:1.82;\r\n}\r\n\r\n\r\n\/* =========================================================\r\n   INTERNAL LINKING\r\n   SIEMPRE \/index.php\/\r\n   ========================================================= *\/\r\n\r\n.etxtrip-related{\r\n    display:flex;\r\n    flex-wrap:wrap;\r\n\r\n    gap:10px;\r\n\r\n    margin-top:30px;\r\n}\r\n\r\n.etxtrip-related a{\r\n    display:inline-flex;\r\n    align-items:center;\r\n\r\n    min-height:43px;\r\n\r\n    padding:10px 15px;\r\n\r\n    border:1px solid var(--border);\r\n    border-radius:10px;\r\n\r\n    background:#fff;\r\n\r\n    color:#111 !important;\r\n\r\n    font-size:12px;\r\n    font-weight:800;\r\n}\r\n\r\n.etxtrip-related a:hover,\r\n.etxtrip-related a:focus{\r\n    background:var(--green);\r\n    border-color:var(--green);\r\n\r\n    color:#111 !important;\r\n}\r\n\r\n\r\n\/* =========================================================\r\n   FAQ\r\n   ========================================================= *\/\r\n\r\n.etxtrip-faq{\r\n    background:#fff;\r\n}\r\n\r\n.etxtrip-faq-grid{\r\n    display:grid;\r\n    grid-template-columns:.75fr 1.25fr;\r\n\r\n    gap:75px;\r\n}\r\n\r\n.etxtrip-faq-list{\r\n    border-top:1px solid var(--border);\r\n}\r\n\r\n.etxtrip-faq-item{\r\n    border-bottom:1px solid var(--border);\r\n}\r\n\r\n.etxtrip-faq-question{\r\n    width:100%;\r\n\r\n    display:flex;\r\n    align-items:center;\r\n    justify-content:space-between;\r\n\r\n    gap:20px;\r\n\r\n    padding:22px 0;\r\n\r\n    border:0;\r\n\r\n    background:transparent;\r\n\r\n    color:#111;\r\n\r\n    text-align:left;\r\n\r\n    font-family:inherit;\r\n\r\n    font-size:15px;\r\n    font-weight:800;\r\n\r\n    cursor:pointer;\r\n}\r\n\r\n.etxtrip-faq-plus{\r\n    width:29px;\r\n    height:29px;\r\n\r\n    flex:0 0 29px;\r\n\r\n    display:flex;\r\n    align-items:center;\r\n    justify-content:center;\r\n\r\n    border-radius:50%;\r\n\r\n    background:var(--soft);\r\n\r\n    font-size:18px;\r\n\r\n    transition:\r\n        transform .25s ease,\r\n        background .25s ease;\r\n}\r\n\r\n.etxtrip-faq-answer{\r\n    display:none;\r\n\r\n    max-width:700px;\r\n\r\n    padding:0 35px 22px 0;\r\n\r\n    color:var(--text);\r\n\r\n    font-size:13px;\r\n    line-height:1.72;\r\n}\r\n\r\n.etxtrip-faq-item.active .etxtrip-faq-answer{\r\n    display:block;\r\n}\r\n\r\n.etxtrip-faq-item.active .etxtrip-faq-plus{\r\n    transform:rotate(45deg);\r\n\r\n    background:var(--green);\r\n}\r\n\r\n\r\n\/* =========================================================\r\n   CTA\r\n   ========================================================= *\/\r\n\r\n.etxtrip-cta{\r\n    position:relative;\r\n\r\n    min-height:610px;\r\n\r\n    display:flex;\r\n    align-items:center;\r\n\r\n    isolation:isolate;\r\n\r\n    background:#111;\r\n}\r\n\r\n.etxtrip-cta-bg{\r\n    position:absolute;\r\n    inset:0;\r\n\r\n    z-index:-3;\r\n}\r\n\r\n.etxtrip-cta-bg img{\r\n    width:100%;\r\n    height:100%;\r\n\r\n    object-fit:cover;\r\n}\r\n\r\n.etxtrip-cta::before{\r\n    content:\"\";\r\n\r\n    position:absolute;\r\n    inset:0;\r\n\r\n    z-index:-2;\r\n\r\n    background:\r\n        linear-gradient(\r\n            90deg,\r\n            rgba(5,7,5,.95),\r\n            rgba(5,7,5,.80) 50%,\r\n            rgba(5,7,5,.27)\r\n        );\r\n}\r\n\r\n.etxtrip-cta-content{\r\n    max-width:700px;\r\n\r\n    padding:90px 0;\r\n}\r\n\r\n.etxtrip-cta-label{\r\n    margin-bottom:18px;\r\n\r\n    color:var(--green);\r\n\r\n    font-size:12px;\r\n    font-weight:800;\r\n\r\n    letter-spacing:1.5px;\r\n    text-transform:uppercase;\r\n}\r\n\r\n.etxtrip-cta h2{\r\n    margin:0;\r\n\r\n    color:#fff;\r\n\r\n    font-size:clamp(43px,5vw,69px);\r\n    line-height:1;\r\n\r\n    font-weight:800;\r\n    letter-spacing:-3px;\r\n}\r\n\r\n.etxtrip-cta p{\r\n    max-width:610px;\r\n\r\n    margin:23px 0 0;\r\n\r\n    color:rgba(255,255,255,.76);\r\n\r\n    font-size:16px;\r\n    line-height:1.72;\r\n}\r\n\r\n.etxtrip-cta a:hover,\r\n.etxtrip-cta a:focus{\r\n    color:#fff !important;\r\n}\r\n\r\n\r\n\/* =========================================================\r\n   TABLET\r\n   ========================================================= *\/\r\n\r\n@media(max-width:1024px){\r\n\r\n    .etxtrip-intro-grid,\r\n    .etxtrip-beach-grid,\r\n    .etxtrip-golf-grid,\r\n    .etxtrip-hotels-grid{\r\n        gap:45px;\r\n    }\r\n\r\n}\r\n\r\n\r\n\/* =========================================================\r\n   M\u00d3VIL\r\n   ========================================================= *\/\r\n\r\n@media(max-width:767px){\r\n\r\n    .etxtrip-wrap{\r\n        width:calc(100% - 32px);\r\n    }\r\n\r\n    .etxtrip-section{\r\n        padding:68px 0;\r\n    }\r\n\r\n    .etxtrip-title{\r\n        font-size:38px;\r\n\r\n        letter-spacing:-1.5px;\r\n    }\r\n\r\n    .etxtrip-text{\r\n        font-size:15px;\r\n    }\r\n\r\n\r\n    \/* HERO *\/\r\n\r\n    .etxtrip-hero{\r\n        min-height:700px;\r\n    }\r\n\r\n    .etxtrip-hero::before{\r\n        background:\r\n            linear-gradient(\r\n                to bottom,\r\n                rgba(5,7,5,.55),\r\n                rgba(5,7,5,.90)\r\n            );\r\n    }\r\n\r\n    .etxtrip-hero-bg img{\r\n        object-position:58% center;\r\n    }\r\n\r\n    .etxtrip-hero-content{\r\n        padding:80px 0 65px;\r\n    }\r\n\r\n    .etxtrip-hero h1{\r\n        font-size:45px;\r\n\r\n        letter-spacing:-2.1px;\r\n    }\r\n\r\n    .etxtrip-hero-text{\r\n        font-size:15px;\r\n    }\r\n\r\n    .etxtrip-btns{\r\n        display:grid;\r\n\r\n        grid-template-columns:1fr;\r\n    }\r\n\r\n    .etxtrip-btn{\r\n        width:100%;\r\n    }\r\n\r\n\r\n    \/* INTRO *\/\r\n\r\n    .etxtrip-intro-grid{\r\n        grid-template-columns:1fr;\r\n\r\n        gap:45px;\r\n    }\r\n\r\n    .etxtrip-intro-photo img{\r\n        height:470px;\r\n    }\r\n\r\n    .etxtrip-floating{\r\n        right:12px;\r\n        bottom:12px;\r\n\r\n        width:190px;\r\n    }\r\n\r\n\r\n    \/* TIPOS *\/\r\n\r\n    .etxtrip-types-grid{\r\n        grid-template-columns:1fr;\r\n    }\r\n\r\n\r\n    \/* PLAYAS *\/\r\n\r\n    .etxtrip-beach-grid{\r\n        grid-template-columns:1fr;\r\n\r\n        gap:43px;\r\n    }\r\n\r\n    .etxtrip-beach-images{\r\n        order:2;\r\n\r\n        gap:9px;\r\n    }\r\n\r\n    .etxtrip-beach-images img:first-child{\r\n        height:385px;\r\n    }\r\n\r\n    .etxtrip-beach-images img:last-child{\r\n        height:290px;\r\n\r\n        margin-top:38px;\r\n    }\r\n\r\n\r\n    \/* GOLF *\/\r\n\r\n    .etxtrip-golf-grid{\r\n        grid-template-columns:1fr;\r\n\r\n        gap:40px;\r\n    }\r\n\r\n    .etxtrip-golf-photo{\r\n        order:2;\r\n    }\r\n\r\n    .etxtrip-golf-photo img{\r\n        height:430px;\r\n    }\r\n\r\n\r\n    \/* HOTELES *\/\r\n\r\n    .etxtrip-hotels-grid{\r\n        grid-template-columns:1fr;\r\n\r\n        gap:40px;\r\n    }\r\n\r\n    .etxtrip-hotels-photo{\r\n        order:2;\r\n    }\r\n\r\n    .etxtrip-hotels-photo img{\r\n        height:430px;\r\n    }\r\n\r\n\r\n    \/* CARRETERA *\/\r\n\r\n    .etxtrip-road{\r\n        min-height:590px;\r\n    }\r\n\r\n    .etxtrip-road::before{\r\n        background:rgba(5,7,5,.72);\r\n    }\r\n\r\n    .etxtrip-road-bg img{\r\n        object-position:60% center;\r\n    }\r\n\r\n\r\n    \/* PROCESO *\/\r\n\r\n    .etxtrip-process-grid{\r\n        grid-template-columns:1fr;\r\n    }\r\n\r\n\r\n    \/* SEO *\/\r\n\r\n    .etxtrip-seo{\r\n        padding:65px 0;\r\n    }\r\n\r\n    .etxtrip-seo h2{\r\n        font-size:34px;\r\n    }\r\n\r\n\r\n    \/* FAQ *\/\r\n\r\n    .etxtrip-faq-grid{\r\n        grid-template-columns:1fr;\r\n\r\n        gap:35px;\r\n    }\r\n\r\n\r\n    \/* CTA *\/\r\n\r\n    .etxtrip-cta{\r\n        min-height:590px;\r\n    }\r\n\r\n    .etxtrip-cta::before{\r\n        background:rgba(5,7,5,.73);\r\n    }\r\n\r\n    .etxtrip-cta-bg img{\r\n        object-position:60% center;\r\n    }\r\n\r\n    .etxtrip-cta h2{\r\n        font-size:45px;\r\n\r\n        letter-spacing:-2px;\r\n    }\r\n\r\n}\r\n<\/style>\r\n\r\n\r\n<main class=\"etxtrip-page\">\r\n\r\n\r\n<!-- =====================================================\r\n     HERO\r\n     ===================================================== -->\r\n\r\n<section class=\"etxtrip-hero\">\r\n\r\n    <div class=\"etxtrip-hero-bg\">\r\n\r\n        <img decoding=\"async\"\r\n            src=\"https:\/\/taxilamangacartagena.es\/wp-content\/uploads\/2026\/08\/taxi-excursiones-cartagena-region-murcia.jpg\"\r\n            alt=\"Taxi para excursiones desde Cartagena y La Manga\"\r\n            fetchpriority=\"high\"\r\n        >\r\n\r\n    <\/div>\r\n\r\n\r\n    <div class=\"etxtrip-wrap\">\r\n\r\n        <div class=\"etxtrip-hero-content\">\r\n\r\n            <div class=\"etxtrip-hero-label\">\r\n                EUROTAXI \u00b7 EXCURSIONES Y TRASLADOS\r\n            <\/div>\r\n\r\n            <h1>\r\n                Taxi para excursiones desde Cartagena <strong>a tu ritmo<\/strong>\r\n            <\/h1>\r\n\r\n            <p class=\"etxtrip-hero-text\">\r\n                Organiza viajes, excursiones y traslados desde Cartagena,\r\n                La Manga y el Mar Menor. Playas, hoteles, campos de golf,\r\n                turismo y desplazamientos por diferentes puntos de la\r\n                Regi\u00f3n de Murcia.\r\n            <\/p>\r\n\r\n\r\n            <div class=\"etxtrip-btns\">\r\n\r\n                <a\r\n                    class=\"etxtrip-btn etxtrip-btn-green\"\r\n                    href=\"tel:+34686253668\"\r\n                >\r\n                    CONSULTAR VIAJE\r\n                <\/a>\r\n\r\n                <a\r\n                    class=\"etxtrip-btn etxtrip-btn-light\"\r\n                    href=\"https:\/\/wa.me\/34686253668?text=Hola%20EUROTAXI.%20Quiero%20consultar%20una%20excursi%C3%B3n%20o%20traslado.%20Salida%3A%20_____.%20Destino%3A%20_____.%20Fecha%3A%20_____.%20Somos%20_____%20personas.\"\r\n                    target=\"_blank\"\r\n                    rel=\"noopener\"\r\n                >\r\n                    CONSULTAR POR WHATSAPP\r\n                <\/a>\r\n\r\n            <\/div>\r\n\r\n\r\n            <div class=\"etxtrip-points\">\r\n\r\n                <div class=\"etxtrip-point\">\r\n                    <span>\u2713<\/span>\r\n                    Cartagena y La Manga\r\n                <\/div>\r\n\r\n                <div class=\"etxtrip-point\">\r\n                    <span>\u2713<\/span>\r\n                    Playas y turismo\r\n                <\/div>\r\n\r\n                <div class=\"etxtrip-point\">\r\n                    <span>\u2713<\/span>\r\n                    Hoteles y golf\r\n                <\/div>\r\n\r\n                <div class=\"etxtrip-point\">\r\n                    <span>\u2713<\/span>\r\n                    Grupos\r\n                <\/div>\r\n\r\n            <\/div>\r\n\r\n        <\/div>\r\n\r\n    <\/div>\r\n\r\n<\/section>\r\n\r\n\r\n\r\n<!-- =====================================================\r\n     INTRO\r\n     ===================================================== -->\r\n\r\n<section class=\"etxtrip-section etxtrip-intro\">\r\n\r\n    <div class=\"etxtrip-wrap etxtrip-intro-grid\">\r\n\r\n\r\n        <div class=\"etxtrip-intro-photo\">\r\n\r\n            <img decoding=\"async\"\r\n                src=\"https:\/\/taxilamangacartagena.es\/wp-content\/uploads\/2026\/08\/taxi-8-plazas-cartagena-costa.jpg\"\r\n                alt=\"Taxi para viajes por Cartagena y costa de Murcia\"\r\n                loading=\"lazy\"\r\n            >\r\n\r\n            <div class=\"etxtrip-floating\">\r\n\r\n                <strong>\r\n                    T\u00fa eliges el destino\r\n                <\/strong>\r\n\r\n                <span>\r\n                    Cu\u00e9ntanos el trayecto y consulta c\u00f3mo organizar tu viaje.\r\n                <\/span>\r\n\r\n            <\/div>\r\n\r\n        <\/div>\r\n\r\n\r\n        <div>\r\n\r\n            <div class=\"etxtrip-eyebrow\">\r\n                Viajes personalizados\r\n            <\/div>\r\n\r\n            <h2 class=\"etxtrip-title\">\r\n                Mucho m\u00e1s que desplazarse de un punto a otro\r\n            <\/h2>\r\n\r\n            <p class=\"etxtrip-text\">\r\n                Hay trayectos que no son simplemente ir de casa al trabajo.\r\n                Una excursi\u00f3n, un d\u00eda de turismo, una visita a la costa o un\r\n                desplazamiento a un campo de golf necesitan una planificaci\u00f3n\r\n                diferente.\r\n            <\/p>\r\n\r\n            <p class=\"etxtrip-text\">\r\n                Con EUROTAXI puedes consultar viajes desde Cartagena, La Manga\r\n                y diferentes zonas del Mar Menor hacia destinos de la Regi\u00f3n\r\n                de Murcia.\r\n            <\/p>\r\n\r\n\r\n            <div class=\"etxtrip-benefits\">\r\n\r\n\r\n                <div class=\"etxtrip-benefit\">\r\n\r\n                    <span class=\"etxtrip-check\">\u2713<\/span>\r\n\r\n                    <div>\r\n\r\n                        <strong>\r\n                            Trayectos programados\r\n                        <\/strong>\r\n\r\n                        <p>\r\n                            Indica previamente lugar de salida, destino, fecha\r\n                            y horario.\r\n                        <\/p>\r\n\r\n                    <\/div>\r\n\r\n                <\/div>\r\n\r\n\r\n                <div class=\"etxtrip-benefit\">\r\n\r\n                    <span class=\"etxtrip-check\">\u2713<\/span>\r\n\r\n                    <div>\r\n\r\n                        <strong>\r\n                            Viajes para grupos\r\n                        <\/strong>\r\n\r\n                        <p>\r\n                            Consulta disponibilidad cuando viaj\u00e9is varias\r\n                            personas.\r\n                        <\/p>\r\n\r\n                    <\/div>\r\n\r\n                <\/div>\r\n\r\n\r\n                <div class=\"etxtrip-benefit\">\r\n\r\n                    <span class=\"etxtrip-check\">\u2713<\/span>\r\n\r\n                    <div>\r\n\r\n                        <strong>\r\n                            Atenci\u00f3n directa\r\n                        <\/strong>\r\n\r\n                        <p>\r\n                            Expl\u00edcanos el recorrido por tel\u00e9fono o WhatsApp.\r\n                        <\/p>\r\n\r\n                    <\/div>\r\n\r\n                <\/div>\r\n\r\n\r\n            <\/div>\r\n\r\n\r\n            <div class=\"etxtrip-btns\">\r\n\r\n                <a\r\n                    class=\"etxtrip-btn etxtrip-btn-dark\"\r\n                    href=\"https:\/\/wa.me\/34686253668?text=Hola%20EUROTAXI.%20Quiero%20organizar%20un%20viaje.%20Salida%3A%20_____.%20Destino%3A%20_____.%20Fecha%20y%20hora%3A%20_____.\"\r\n                    target=\"_blank\"\r\n                    rel=\"noopener\"\r\n                >\r\n                    CU\u00c9NTANOS TU PLAN\r\n                <\/a>\r\n\r\n            <\/div>\r\n\r\n        <\/div>\r\n\r\n    <\/div>\r\n\r\n<\/section>\r\n\r\n\r\n\r\n<!-- =====================================================\r\n     TIPOS DE TRASLADO\r\n     ===================================================== -->\r\n\r\n<section class=\"etxtrip-section etxtrip-types\">\r\n\r\n    <div class=\"etxtrip-wrap\">\r\n\r\n\r\n        <div class=\"etxtrip-types-head\">\r\n\r\n            <div class=\"etxtrip-eyebrow\">\r\n                Diferentes destinos\r\n            <\/div>\r\n\r\n            <h2 class=\"etxtrip-title\">\r\n                \u00bfD\u00f3nde quieres ir?\r\n            <\/h2>\r\n\r\n            <p class=\"etxtrip-text\">\r\n                Consulta con EUROTAXI diferentes tipos de desplazamiento\r\n                desde Cartagena y La Manga.\r\n            <\/p>\r\n\r\n        <\/div>\r\n\r\n\r\n        <div class=\"etxtrip-types-grid\">\r\n\r\n\r\n            <article class=\"etxtrip-type-card\">\r\n\r\n                <img decoding=\"async\"\r\n                    src=\"https:\/\/taxilamangacartagena.es\/wp-content\/uploads\/2026\/08\/servicio-taxi-playas-cartagena.jpg\"\r\n                    alt=\"Taxi para playas desde Cartagena\"\r\n                    loading=\"lazy\"\r\n                >\r\n\r\n                <div class=\"etxtrip-type-content\">\r\n\r\n                    <div class=\"etxtrip-type-icon\">\r\n                        \u2600\ufe0f\r\n                    <\/div>\r\n\r\n                    <h3>\r\n                        Playas y costa\r\n                    <\/h3>\r\n\r\n                    <p>\r\n                        Desplazamientos hacia zonas costeras, playas y\r\n                        localidades del entorno.\r\n                    <\/p>\r\n\r\n                <\/div>\r\n\r\n            <\/article>\r\n\r\n\r\n            <article class=\"etxtrip-type-card\">\r\n\r\n                <img decoding=\"async\"\r\n                    src=\"https:\/\/taxilamangacartagena.es\/wp-content\/uploads\/2026\/08\/taxi-traslado-golf-cartagena.jpg\"\r\n                    alt=\"Taxi para campos de golf desde Cartagena\"\r\n                    loading=\"lazy\"\r\n                >\r\n\r\n                <div class=\"etxtrip-type-content\">\r\n\r\n                    <div class=\"etxtrip-type-icon\">\r\n                        \u26f3\r\n                    <\/div>\r\n\r\n                    <h3>\r\n                        Campos de golf\r\n                    <\/h3>\r\n\r\n                    <p>\r\n                        Consulta traslados para jugar al golf y desplazamientos\r\n                        con equipamiento deportivo.\r\n                    <\/p>\r\n\r\n                <\/div>\r\n\r\n            <\/article>\r\n\r\n\r\n            <article class=\"etxtrip-type-card\">\r\n\r\n                <img decoding=\"async\"\r\n                    src=\"https:\/\/taxilamangacartagena.es\/wp-content\/uploads\/2026\/08\/taxi-hotel-occidental-mar-menor.jpg\"\r\n                    alt=\"Taxi para hoteles en Cartagena y Mar Menor\"\r\n                    loading=\"lazy\"\r\n                >\r\n\r\n                <div class=\"etxtrip-type-content\">\r\n\r\n                    <div class=\"etxtrip-type-icon\">\r\n                        \ud83c\udfe8\r\n                    <\/div>\r\n\r\n                    <h3>\r\n                        Hoteles\r\n                    <\/h3>\r\n\r\n                    <p>\r\n                        Recogidas y traslados desde hoteles, resorts y\r\n                        alojamientos tur\u00edsticos.\r\n                    <\/p>\r\n\r\n                <\/div>\r\n\r\n            <\/article>\r\n\r\n\r\n            <article class=\"etxtrip-type-card\">\r\n\r\n                <img decoding=\"async\"\r\n                    src=\"https:\/\/taxilamangacartagena.es\/wp-content\/uploads\/2026\/08\/taxi-excursiones-cartagena-region-murcia.jpg\"\r\n                    alt=\"Excursiones en taxi por la Regi\u00f3n de Murcia\"\r\n                    loading=\"lazy\"\r\n                >\r\n\r\n                <div class=\"etxtrip-type-content\">\r\n\r\n                    <div class=\"etxtrip-type-icon\">\r\n                        \ud83d\udcf8\r\n                    <\/div>\r\n\r\n                    <h3>\r\n                        Turismo y excursiones\r\n                    <\/h3>\r\n\r\n                    <p>\r\n                        Consulta viajes tur\u00edsticos y desplazamientos para\r\n                        conocer otros puntos de la Regi\u00f3n.\r\n                    <\/p>\r\n\r\n                <\/div>\r\n\r\n            <\/article>\r\n\r\n\r\n            <article class=\"etxtrip-type-card\">\r\n\r\n                <img decoding=\"async\"\r\n                    src=\"https:\/\/taxilamangacartagena.es\/wp-content\/uploads\/2026\/08\/taxi-equipaje-cartagena.jpg\"\r\n                    alt=\"Taxi para viajeros con equipaje en Cartagena\"\r\n                    loading=\"lazy\"\r\n                >\r\n\r\n                <div class=\"etxtrip-type-content\">\r\n\r\n                    <div class=\"etxtrip-type-icon\">\r\n                        \ud83e\uddf3\r\n                    <\/div>\r\n\r\n                    <h3>\r\n                        Equipaje\r\n                    <\/h3>\r\n\r\n                    <p>\r\n                        Indica las maletas o bultos que llevas para organizar\r\n                        correctamente el trayecto.\r\n                    <\/p>\r\n\r\n                <\/div>\r\n\r\n            <\/article>\r\n\r\n\r\n            <article class=\"etxtrip-type-card\">\r\n\r\n                <img decoding=\"async\"\r\n                    src=\"https:\/\/taxilamangacartagena.es\/wp-content\/uploads\/2026\/08\/taxi-mercedes-8-plazas-cartagena-costa.jpg\"\r\n                    alt=\"Taxi para grupos y excursiones Cartagena\"\r\n                    loading=\"lazy\"\r\n                >\r\n\r\n                <div class=\"etxtrip-type-content\">\r\n\r\n                    <div class=\"etxtrip-type-icon\">\r\n                        \ud83d\udc65\r\n                    <\/div>\r\n\r\n                    <h3>\r\n                        Familias y grupos\r\n                    <\/h3>\r\n\r\n                    <p>\r\n                        Disfrutad del viaje juntos sin necesidad de organizar\r\n                        varios veh\u00edculos.\r\n                    <\/p>\r\n\r\n                <\/div>\r\n\r\n            <\/article>\r\n\r\n\r\n        <\/div>\r\n\r\n    <\/div>\r\n\r\n<\/section>\r\n\r\n\r\n\r\n<!-- =====================================================\r\n     PLAYAS\r\n     ===================================================== -->\r\n\r\n<section class=\"etxtrip-section etxtrip-beach\">\r\n\r\n    <div class=\"etxtrip-wrap etxtrip-beach-grid\">\r\n\r\n\r\n        <div>\r\n\r\n            <div class=\"etxtrip-eyebrow\">\r\n                Mar Mediterr\u00e1neo y Mar Menor\r\n            <\/div>\r\n\r\n            <h2 class=\"etxtrip-title\">\r\n                Taxi para playas y costa desde Cartagena\r\n            <\/h2>\r\n\r\n            <p class=\"etxtrip-text\">\r\n                Disfruta de un d\u00eda en la costa sin preocuparte por conducir,\r\n                buscar aparcamiento o organizar varios veh\u00edculos.\r\n            <\/p>\r\n\r\n            <p class=\"etxtrip-text\">\r\n                Consulta desplazamientos desde Cartagena hacia La Manga,\r\n                Mar Menor y otras zonas costeras.\r\n            <\/p>\r\n\r\n\r\n            <div class=\"etxtrip-btns\">\r\n\r\n                <a\r\n                    class=\"etxtrip-btn etxtrip-btn-green\"\r\n                    href=\"\/index.php\/taxi-la-manga\/\"\r\n                >\r\n                    VER TAXI LA MANGA\r\n                <\/a>\r\n\r\n            <\/div>\r\n\r\n        <\/div>\r\n\r\n\r\n        <div class=\"etxtrip-beach-images\">\r\n\r\n            <img decoding=\"async\"\r\n                src=\"https:\/\/taxilamangacartagena.es\/wp-content\/uploads\/2026\/08\/servicio-taxi-playas-cartagena.jpg\"\r\n                alt=\"Servicio de taxi a playas desde Cartagena\"\r\n                loading=\"lazy\"\r\n            >\r\n\r\n            <img decoding=\"async\"\r\n                src=\"https:\/\/taxilamangacartagena.es\/wp-content\/uploads\/2026\/08\/taxi-mercedes-cartagena-costa.jpg\"\r\n                alt=\"Taxi por la costa de Cartagena\"\r\n                loading=\"lazy\"\r\n            >\r\n\r\n        <\/div>\r\n\r\n    <\/div>\r\n\r\n<\/section>\r\n\r\n\r\n\r\n<!-- =====================================================\r\n     GOLF\r\n     ===================================================== -->\r\n\r\n<section class=\"etxtrip-section etxtrip-golf\">\r\n\r\n    <div class=\"etxtrip-wrap etxtrip-golf-grid\">\r\n\r\n\r\n        <div>\r\n\r\n            <div class=\"etxtrip-eyebrow\">\r\n                Golf y deporte\r\n            <\/div>\r\n\r\n            <h2 class=\"etxtrip-title\">\r\n                Taxi para campos de golf en la Regi\u00f3n de Murcia\r\n            <\/h2>\r\n\r\n            <p class=\"etxtrip-text\">\r\n                Si necesitas desplazarte desde Cartagena, La Manga o tu hotel\r\n                hacia un campo de golf, puedes consultar previamente el\r\n                recorrido con EUROTAXI.\r\n            <\/p>\r\n\r\n            <p class=\"etxtrip-text\">\r\n                Cuando lleves bolsas de golf o cualquier material deportivo,\r\n                ind\u00edcalo en la reserva para comprobar el espacio necesario.\r\n            <\/p>\r\n\r\n\r\n            <div class=\"etxtrip-tags\">\r\n\r\n                <span class=\"etxtrip-tag\">\r\n                    Golf\r\n                <\/span>\r\n\r\n                <span class=\"etxtrip-tag\">\r\n                    Equipamiento\r\n                <\/span>\r\n\r\n                <span class=\"etxtrip-tag\">\r\n                    Hoteles\r\n                <\/span>\r\n\r\n                <span class=\"etxtrip-tag\">\r\n                    Grupos\r\n                <\/span>\r\n\r\n                <span class=\"etxtrip-tag\">\r\n                    Cartagena\r\n                <\/span>\r\n\r\n                <span class=\"etxtrip-tag\">\r\n                    La Manga\r\n                <\/span>\r\n\r\n            <\/div>\r\n\r\n\r\n            <div class=\"etxtrip-btns\">\r\n\r\n                <a\r\n                    class=\"etxtrip-btn etxtrip-btn-dark\"\r\n                    href=\"https:\/\/wa.me\/34686253668?text=Hola%20EUROTAXI.%20Quiero%20consultar%20un%20traslado%20a%20un%20campo%20de%20golf.%20Salida%3A%20_____.%20Destino%3A%20_____.%20Somos%20_____%20personas.\"\r\n                    target=\"_blank\"\r\n                    rel=\"noopener\"\r\n                >\r\n                    CONSULTAR TRASLADO\r\n                <\/a>\r\n\r\n            <\/div>\r\n\r\n        <\/div>\r\n\r\n\r\n        <div class=\"etxtrip-golf-photo\">\r\n\r\n            <img decoding=\"async\"\r\n                src=\"https:\/\/taxilamangacartagena.es\/wp-content\/uploads\/2026\/08\/taxi-traslado-golf-cartagena.jpg\"\r\n                alt=\"Traslado en taxi a campos de golf Cartagena\"\r\n                loading=\"lazy\"\r\n            >\r\n\r\n        <\/div>\r\n\r\n    <\/div>\r\n\r\n<\/section>\r\n\r\n\r\n\r\n<!-- =====================================================\r\n     HOTELES\r\n     ===================================================== -->\r\n\r\n<section class=\"etxtrip-section etxtrip-hotels\">\r\n\r\n    <div class=\"etxtrip-wrap etxtrip-hotels-grid\">\r\n\r\n\r\n        <div class=\"etxtrip-hotels-photo\">\r\n\r\n            <img decoding=\"async\"\r\n                src=\"https:\/\/taxilamangacartagena.es\/wp-content\/uploads\/2026\/08\/taxi-hotel-occidental-mar-menor.jpg\"\r\n                alt=\"Taxi para hoteles de Cartagena y Mar Menor\"\r\n                loading=\"lazy\"\r\n            >\r\n\r\n        <\/div>\r\n\r\n\r\n        <div>\r\n\r\n            <div class=\"etxtrip-eyebrow\">\r\n                Hoteles y resorts\r\n            <\/div>\r\n\r\n            <h2 class=\"etxtrip-title\">\r\n                Recogidas desde hoteles y alojamientos\r\n            <\/h2>\r\n\r\n            <p class=\"etxtrip-text\">\r\n                \u00bfEst\u00e1s alojado en Cartagena, La Manga o el Mar Menor?\r\n                Podemos recoger tu solicitud de traslado directamente desde\r\n                el hotel o alojamiento.\r\n            <\/p>\r\n\r\n            <p class=\"etxtrip-text\">\r\n                Desde all\u00ed puedes consultar viajes hacia Cartagena, playas,\r\n                campos de golf, aeropuerto o cualquier otro destino.\r\n            <\/p>\r\n\r\n\r\n            <div class=\"etxtrip-btns\">\r\n\r\n                <a\r\n                    class=\"etxtrip-btn etxtrip-btn-dark\"\r\n                    href=\"https:\/\/wa.me\/34686253668?text=Hola%20EUROTAXI.%20Necesito%20una%20recogida%20en%20un%20hotel.%20Hotel%3A%20_____.%20Destino%3A%20_____.%20Fecha%20y%20hora%3A%20_____.\"\r\n                    target=\"_blank\"\r\n                    rel=\"noopener\"\r\n                >\r\n                    RESERVAR RECOGIDA\r\n                <\/a>\r\n\r\n            <\/div>\r\n\r\n        <\/div>\r\n\r\n    <\/div>\r\n\r\n<\/section>\r\n\r\n\r\n\r\n<!-- =====================================================\r\n     CARRETERA\r\n     ===================================================== -->\r\n\r\n<section class=\"etxtrip-road\">\r\n\r\n    <div class=\"etxtrip-road-bg\">\r\n\r\n        <img decoding=\"async\"\r\n            src=\"https:\/\/taxilamangacartagena.es\/wp-content\/uploads\/2026\/08\/traslados-carretera-taxi-cartagena.jpeg\"\r\n            alt=\"Viajes y traslados por carretera desde Cartagena\"\r\n            loading=\"lazy\"\r\n        >\r\n\r\n    <\/div>\r\n\r\n\r\n    <div class=\"etxtrip-wrap\">\r\n\r\n        <div class=\"etxtrip-road-content\">\r\n\r\n            <div class=\"etxtrip-eyebrow\">\r\n                Viajes por carretera\r\n            <\/div>\r\n\r\n            <h2 class=\"etxtrip-title\">\r\n                Un destino diferente tambi\u00e9n puede empezar en Cartagena\r\n            <\/h2>\r\n\r\n            <p class=\"etxtrip-text\">\r\n                Si necesitas realizar un desplazamiento fuera de tu recorrido\r\n                habitual, cu\u00e9ntanos el origen y destino. Podemos comprobar la\r\n                disponibilidad para viajes programados por carretera.\r\n            <\/p>\r\n\r\n\r\n            <div class=\"etxtrip-btns\">\r\n\r\n                <a\r\n                    class=\"etxtrip-btn etxtrip-btn-green\"\r\n                    href=\"https:\/\/wa.me\/34686253668?text=Hola%20EUROTAXI.%20Quiero%20consultar%20un%20viaje%20por%20carretera.%20Salida%3A%20_____.%20Destino%3A%20_____.%20Fecha%3A%20_____.\"\r\n                    target=\"_blank\"\r\n                    rel=\"noopener\"\r\n                >\r\n                    CONSULTAR DESTINO\r\n                <\/a>\r\n\r\n            <\/div>\r\n\r\n        <\/div>\r\n\r\n    <\/div>\r\n\r\n<\/section>\r\n\r\n\r\n\r\n<!-- =====================================================\r\n     RESERVA\r\n     ===================================================== -->\r\n\r\n<section class=\"etxtrip-section etxtrip-process\">\r\n\r\n    <div class=\"etxtrip-wrap\">\r\n\r\n\r\n        <div class=\"etxtrip-process-head\">\r\n\r\n            <div class=\"etxtrip-eyebrow\">\r\n                Organiza tu trayecto\r\n            <\/div>\r\n\r\n            <h2 class=\"etxtrip-title\">\r\n                Reserva tu excursi\u00f3n en tres pasos\r\n            <\/h2>\r\n\r\n        <\/div>\r\n\r\n\r\n        <div class=\"etxtrip-process-grid\">\r\n\r\n\r\n            <article class=\"etxtrip-process-card\">\r\n\r\n                <div class=\"etxtrip-process-num\">\r\n                    01\r\n                <\/div>\r\n\r\n                <h3>\r\n                    Cu\u00e9ntanos el recorrido\r\n                <\/h3>\r\n\r\n                <p>\r\n                    Indica desde d\u00f3nde quieres salir y cu\u00e1l ser\u00e1 el destino.\r\n                <\/p>\r\n\r\n            <\/article>\r\n\r\n\r\n            <article class=\"etxtrip-process-card\">\r\n\r\n                <div class=\"etxtrip-process-num\">\r\n                    02\r\n                <\/div>\r\n\r\n                <h3>\r\n                    Fecha y pasajeros\r\n                <\/h3>\r\n\r\n                <p>\r\n                    Dinos cu\u00e1ndo quieres viajar, cu\u00e1ntas personas sois y si\r\n                    llev\u00e1is equipaje.\r\n                <\/p>\r\n\r\n            <\/article>\r\n\r\n\r\n            <article class=\"etxtrip-process-card\">\r\n\r\n                <div class=\"etxtrip-process-num\">\r\n                    03\r\n                <\/div>\r\n\r\n                <h3>\r\n                    Confirma disponibilidad\r\n                <\/h3>\r\n\r\n                <p>\r\n                    Contacta directamente con EUROTAXI para organizar el\r\n                    servicio.\r\n                <\/p>\r\n\r\n            <\/article>\r\n\r\n\r\n        <\/div>\r\n\r\n    <\/div>\r\n\r\n<\/section>\r\n\r\n\r\n\r\n<!-- =====================================================\r\n     SEO + INTERNAL LINKING\r\n     ===================================================== -->\r\n\r\n<section class=\"etxtrip-seo\">\r\n\r\n    <div class=\"etxtrip-wrap\">\r\n\r\n        <div class=\"etxtrip-seo-inner\">\r\n\r\n            <h2>\r\n                Taxi para excursiones y traslados desde Cartagena\r\n            <\/h2>\r\n\r\n            <p>\r\n                Si buscas un taxi para excursiones en Cartagena, EUROTAXI te\r\n                permite consultar desplazamientos programados hacia playas,\r\n                hoteles, zonas tur\u00edsticas, campos de golf y diferentes\r\n                destinos de la Regi\u00f3n de Murcia. Tambi\u00e9n puedes organizar\r\n                viajes desde La Manga y el Mar Menor.\r\n            <\/p>\r\n\r\n            <p>\r\n                Para solicitar un traslado, indica punto de salida, destino,\r\n                fecha, horario y n\u00famero de pasajeros. Si viajas con equipaje,\r\n                material deportivo o un grupo numeroso, es recomendable\r\n                comunicarlo al realizar la reserva para organizar\r\n                correctamente el servicio.\r\n            <\/p>\r\n\r\n\r\n            <div class=\"etxtrip-related\">\r\n\r\n                <a href=\"\/index.php\/taxi-la-manga\/\">\r\n                    Taxi La Manga\r\n                <\/a>\r\n\r\n                <a href=\"\/index.php\/taxi-aeropuerto-cartagena\/\">\r\n                    Taxi aeropuerto Cartagena\r\n                <\/a>\r\n\r\n                <a href=\"\/index.php\/taxi-8-plazas-cartagena\/\">\r\n                    Taxi 8 plazas Cartagena\r\n                <\/a>\r\n\r\n                <a href=\"\/index.php\/taxi-adaptado-cartagena\/\">\r\n                    Taxi adaptado Cartagena\r\n                <\/a>\r\n\r\n            <\/div>\r\n\r\n        <\/div>\r\n\r\n    <\/div>\r\n\r\n<\/section>\r\n\r\n\r\n\r\n<!-- =====================================================\r\n     FAQ\r\n     ===================================================== -->\r\n\r\n<section class=\"etxtrip-section etxtrip-faq\">\r\n\r\n    <div class=\"etxtrip-wrap etxtrip-faq-grid\">\r\n\r\n\r\n        <div>\r\n\r\n            <div class=\"etxtrip-eyebrow\">\r\n                Preguntas frecuentes\r\n            <\/div>\r\n\r\n            <h2 class=\"etxtrip-title\">\r\n                Excursiones y traslados\r\n            <\/h2>\r\n\r\n        <\/div>\r\n\r\n\r\n        <div class=\"etxtrip-faq-list\">\r\n\r\n\r\n            <div class=\"etxtrip-faq-item active\">\r\n\r\n                <button\r\n                    class=\"etxtrip-faq-question\"\r\n                    type=\"button\"\r\n                >\r\n                    \u00bfPuedo reservar un taxi para una excursi\u00f3n desde Cartagena?\r\n\r\n                    <span class=\"etxtrip-faq-plus\">+<\/span>\r\n                <\/button>\r\n\r\n                <div class=\"etxtrip-faq-answer\">\r\n                    S\u00ed. Puedes consultar un viaje programado indicando origen,\r\n                    destino, fecha, horario y n\u00famero de pasajeros.\r\n                <\/div>\r\n\r\n            <\/div>\r\n\r\n\r\n            <div class=\"etxtrip-faq-item\">\r\n\r\n                <button\r\n                    class=\"etxtrip-faq-question\"\r\n                    type=\"button\"\r\n                >\r\n                    \u00bfRealiz\u00e1is traslados a playas?\r\n\r\n                    <span class=\"etxtrip-faq-plus\">+<\/span>\r\n                <\/button>\r\n\r\n                <div class=\"etxtrip-faq-answer\">\r\n                    Puedes consultar desplazamientos desde Cartagena hacia\r\n                    La Manga, Mar Menor y otras zonas costeras del entorno.\r\n                <\/div>\r\n\r\n            <\/div>\r\n\r\n\r\n            <div class=\"etxtrip-faq-item\">\r\n\r\n                <button\r\n                    class=\"etxtrip-faq-question\"\r\n                    type=\"button\"\r\n                >\r\n                    \u00bfPuedo reservar un taxi para ir a jugar al golf?\r\n\r\n                    <span class=\"etxtrip-faq-plus\">+<\/span>\r\n                <\/button>\r\n\r\n                <div class=\"etxtrip-faq-answer\">\r\n                    S\u00ed. Indica el campo de golf, punto de recogida, n\u00famero de\r\n                    pasajeros y si llevas equipamiento deportivo.\r\n                <\/div>\r\n\r\n            <\/div>\r\n\r\n\r\n            <div class=\"etxtrip-faq-item\">\r\n\r\n                <button\r\n                    class=\"etxtrip-faq-question\"\r\n                    type=\"button\"\r\n                >\r\n                    \u00bfHac\u00e9is recogidas en hoteles?\r\n\r\n                    <span class=\"etxtrip-faq-plus\">+<\/span>\r\n                <\/button>\r\n\r\n                <div class=\"etxtrip-faq-answer\">\r\n                    S\u00ed. Puedes indicar el nombre o direcci\u00f3n del hotel y el\r\n                    destino al realizar tu consulta.\r\n                <\/div>\r\n\r\n            <\/div>\r\n\r\n\r\n            <div class=\"etxtrip-faq-item\">\r\n\r\n                <button\r\n                    class=\"etxtrip-faq-question\"\r\n                    type=\"button\"\r\n                >\r\n                    \u00bfPodemos realizar la excursi\u00f3n varias personas?\r\n\r\n                    <span class=\"etxtrip-faq-plus\">+<\/span>\r\n                <\/button>\r\n\r\n                <div class=\"etxtrip-faq-answer\">\r\n                    S\u00ed. EUROTAXI dispone de servicio para grupos. Indica el\r\n                    n\u00famero de pasajeros al reservar para confirmar\r\n                    disponibilidad.\r\n                <\/div>\r\n\r\n            <\/div>\r\n\r\n\r\n            <div class=\"etxtrip-faq-item\">\r\n\r\n                <button\r\n                    class=\"etxtrip-faq-question\"\r\n                    type=\"button\"\r\n                >\r\n                    \u00bfC\u00f3mo puedo pedir informaci\u00f3n?\r\n\r\n                    <span class=\"etxtrip-faq-plus\">+<\/span>\r\n                <\/button>\r\n\r\n                <div class=\"etxtrip-faq-answer\">\r\n                    Puedes llamar al 686 253 668 o escribir directamente por\r\n                    WhatsApp con los datos del trayecto.\r\n                <\/div>\r\n\r\n            <\/div>\r\n\r\n\r\n        <\/div>\r\n\r\n    <\/div>\r\n\r\n<\/section>\r\n\r\n\r\n\r\n<!-- =====================================================\r\n     CTA FINAL\r\n     ===================================================== -->\r\n\r\n<section class=\"etxtrip-cta\">\r\n\r\n    <div class=\"etxtrip-cta-bg\">\r\n\r\n        <img decoding=\"async\"\r\n            src=\"https:\/\/taxilamangacartagena.es\/wp-content\/uploads\/2026\/08\/vehiculo-eurotaxi-cartagena-mercedes.jpg\"\r\n            alt=\"Reservar excursi\u00f3n en Eurotaxi Cartagena\"\r\n            loading=\"lazy\"\r\n        >\r\n\r\n    <\/div>\r\n\r\n\r\n    <div class=\"etxtrip-wrap\">\r\n\r\n        <div class=\"etxtrip-cta-content\">\r\n\r\n            <div class=\"etxtrip-cta-label\">\r\n                T\u00fa eliges el destino\r\n            <\/div>\r\n\r\n            <h2>\r\n                Cu\u00e9ntanos d\u00f3nde quieres ir.\r\n            <\/h2>\r\n\r\n            <p>\r\n                Expl\u00edcanos tu trayecto, fecha y n\u00famero de pasajeros.\r\n                Consulta directamente con EUROTAXI tu pr\u00f3xima excursi\u00f3n o\r\n                traslado.\r\n            <\/p>\r\n\r\n\r\n            <div class=\"etxtrip-btns\">\r\n\r\n                <a\r\n                    class=\"etxtrip-btn etxtrip-btn-green\"\r\n                    href=\"https:\/\/wa.me\/34686253668?text=Hola%20EUROTAXI.%20Quiero%20consultar%20una%20excursi%C3%B3n%20o%20traslado.%20Salida%3A%20_____.%20Destino%3A%20_____.%20Fecha%3A%20_____.%20Somos%20_____%20personas.\"\r\n                    target=\"_blank\"\r\n                    rel=\"noopener\"\r\n                >\r\n                    CONSULTAR POR WHATSAPP\r\n                <\/a>\r\n\r\n                <a\r\n                    class=\"etxtrip-btn etxtrip-btn-light\"\r\n                    href=\"tel:+34686253668\"\r\n                >\r\n                    LLAMAR AL 686 253 668\r\n                <\/a>\r\n\r\n            <\/div>\r\n\r\n        <\/div>\r\n\r\n    <\/div>\r\n\r\n<\/section>\r\n\r\n\r\n<\/main>\r\n\r\n\r\n\r\n<!-- =====================================================\r\n     FAQ SCHEMA\r\n     ===================================================== -->\r\n\r\n<script type=\"application\/ld+json\">\r\n{\r\n    \"@context\":\"https:\/\/schema.org\",\r\n    \"@type\":\"FAQPage\",\r\n    \"mainEntity\":[\r\n        {\r\n            \"@type\":\"Question\",\r\n            \"name\":\"\u00bfPuedo reservar un taxi para una excursi\u00f3n desde Cartagena?\",\r\n            \"acceptedAnswer\":{\r\n                \"@type\":\"Answer\",\r\n                \"text\":\"S\u00ed. Puedes consultar un viaje programado indicando origen, destino, fecha, horario y n\u00famero de pasajeros.\"\r\n            }\r\n        },\r\n        {\r\n            \"@type\":\"Question\",\r\n            \"name\":\"\u00bfRealiz\u00e1is traslados a playas?\",\r\n            \"acceptedAnswer\":{\r\n                \"@type\":\"Answer\",\r\n                \"text\":\"Puedes consultar desplazamientos desde Cartagena hacia La Manga, Mar Menor y otras zonas costeras del entorno.\"\r\n            }\r\n        },\r\n        {\r\n            \"@type\":\"Question\",\r\n            \"name\":\"\u00bfPuedo reservar un taxi para ir a jugar al golf?\",\r\n            \"acceptedAnswer\":{\r\n                \"@type\":\"Answer\",\r\n                \"text\":\"S\u00ed. Indica el campo de golf, punto de recogida, n\u00famero de pasajeros y si llevas equipamiento deportivo.\"\r\n            }\r\n        },\r\n        {\r\n            \"@type\":\"Question\",\r\n            \"name\":\"\u00bfHac\u00e9is recogidas en hoteles?\",\r\n            \"acceptedAnswer\":{\r\n                \"@type\":\"Answer\",\r\n                \"text\":\"S\u00ed. Puedes indicar el nombre o direcci\u00f3n del hotel y el destino al realizar tu consulta.\"\r\n            }\r\n        },\r\n        {\r\n            \"@type\":\"Question\",\r\n            \"name\":\"\u00bfPodemos realizar la excursi\u00f3n varias personas?\",\r\n            \"acceptedAnswer\":{\r\n                \"@type\":\"Answer\",\r\n                \"text\":\"S\u00ed. EUROTAXI dispone de servicio para grupos. Indica el n\u00famero de pasajeros al reservar para confirmar disponibilidad.\"\r\n            }\r\n        },\r\n        {\r\n            \"@type\":\"Question\",\r\n            \"name\":\"\u00bfC\u00f3mo puedo pedir informaci\u00f3n?\",\r\n            \"acceptedAnswer\":{\r\n                \"@type\":\"Answer\",\r\n                \"text\":\"Puedes llamar al 686 253 668 o escribir directamente por WhatsApp con los datos del trayecto.\"\r\n            }\r\n        }\r\n    ]\r\n}\r\n<\/script>\r\n\r\n\r\n\r\n<!-- =====================================================\r\n     SERVICE SCHEMA\r\n     ===================================================== -->\r\n\r\n<script type=\"application\/ld+json\">\r\n{\r\n    \"@context\":\"https:\/\/schema.org\",\r\n    \"@type\":\"Service\",\r\n    \"name\":\"Taxi para excursiones en Cartagena\",\r\n    \"serviceType\":\"Excursiones y traslados en taxi\",\r\n    \"provider\":{\r\n        \"@type\":\"LocalBusiness\",\r\n        \"name\":\"EUROTAXI\",\r\n        \"telephone\":\"+34686253668\",\r\n        \"email\":\"info@taxilamangacartagena.es\",\r\n        \"url\":\"https:\/\/taxilamangacartagena.es\/\"\r\n    },\r\n    \"areaServed\":[\r\n        {\r\n            \"@type\":\"City\",\r\n            \"name\":\"Cartagena\"\r\n        },\r\n        {\r\n            \"@type\":\"Place\",\r\n            \"name\":\"La Manga del Mar Menor\"\r\n        },\r\n        {\r\n            \"@type\":\"AdministrativeArea\",\r\n            \"name\":\"Regi\u00f3n de Murcia\"\r\n        }\r\n    ],\r\n    \"url\":\"https:\/\/taxilamangacartagena.es\/index.php\/taxi-excursiones-cartagena\/\"\r\n}\r\n<\/script>\r\n\r\n\r\n\r\n<script>\r\ndocument.addEventListener(\"DOMContentLoaded\",function(){\r\n\r\n    const questions =\r\n        document.querySelectorAll(\r\n            \".etxtrip-faq-question\"\r\n        );\r\n\r\n    questions.forEach(function(question){\r\n\r\n        question.addEventListener(\r\n            \"click\",\r\n            function(){\r\n\r\n                const item =\r\n                    this.closest(\r\n                        \".etxtrip-faq-item\"\r\n                    );\r\n\r\n                item.classList.toggle(\r\n                    \"active\"\r\n                );\r\n\r\n            }\r\n        );\r\n\r\n    });\r\n\r\n});\r\n<\/script>\t\t\t\t<\/div>\n\t\t\n<\/div>\n\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>EUROTAXI \u00b7 EXCURSIONES Y TRASLADOS Taxi para excursiones desde Cartagena a tu ritmo Organiza viajes, excursiones y traslados desde Cartagena, La Manga y el Mar Menor. Playas, hoteles, campos de golf, turismo y desplazamientos por diferentes puntos de la Regi\u00f3n de Murcia. CONSULTAR VIAJE CONSULTAR POR WHATSAPP \u2713 Cartagena y La Manga \u2713 Playas y &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/taxilamangacartagena.es\/index.php\/taxi-excursiones-cartagena\/\" class=\"more-link\">Leer m\u00e1s<span class=\"screen-reader-text\"> \u00abExcursiones y Traslados\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inspiro_hide_title":false,"inspiro_hide_featured_image":false,"footnotes":""},"class_list":["post-96","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Excursiones y Traslados - Eurotaxi<\/title>\n<meta name=\"description\" content=\"Descubre Cartagena con Eurotaxi: excursiones personalizadas y traslados c\u00f3modos. Viaja a tu ritmo y disfruta cada momento. \u00a1Reserva ahora!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/taxilamangacartagena.es\/index.php\/taxi-excursiones-cartagena\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Excursiones y Traslados - Eurotaxi\" \/>\n<meta property=\"og:description\" content=\"Descubre Cartagena con Eurotaxi: excursiones personalizadas y traslados c\u00f3modos. Viaja a tu ritmo y disfruta cada momento. \u00a1Reserva ahora!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/taxilamangacartagena.es\/index.php\/taxi-excursiones-cartagena\/\" \/>\n<meta property=\"og:site_name\" content=\"Eurotaxi\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-27T22:03:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/taxilamangacartagena.es\/wp-content\/uploads\/2026\/08\/taxi-excursiones-cartagena-region-murcia.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/taxilamangacartagena.es\\\/index.php\\\/taxi-excursiones-cartagena\\\/\",\"url\":\"https:\\\/\\\/taxilamangacartagena.es\\\/index.php\\\/taxi-excursiones-cartagena\\\/\",\"name\":\"Excursiones y Traslados - Eurotaxi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/taxilamangacartagena.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/taxilamangacartagena.es\\\/index.php\\\/taxi-excursiones-cartagena\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/taxilamangacartagena.es\\\/index.php\\\/taxi-excursiones-cartagena\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/taxilamangacartagena.es\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/taxi-excursiones-cartagena-region-murcia.jpg\",\"datePublished\":\"2026-08-27T20:23:38+00:00\",\"dateModified\":\"2026-08-27T22:03:29+00:00\",\"description\":\"Descubre Cartagena con Eurotaxi: excursiones personalizadas y traslados c\u00f3modos. Viaja a tu ritmo y disfruta cada momento. \u00a1Reserva ahora!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/taxilamangacartagena.es\\\/index.php\\\/taxi-excursiones-cartagena\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/taxilamangacartagena.es\\\/index.php\\\/taxi-excursiones-cartagena\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/taxilamangacartagena.es\\\/index.php\\\/taxi-excursiones-cartagena\\\/#primaryimage\",\"url\":\"https:\\\/\\\/taxilamangacartagena.es\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/taxi-excursiones-cartagena-region-murcia.jpg\",\"contentUrl\":\"https:\\\/\\\/taxilamangacartagena.es\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/taxi-excursiones-cartagena-region-murcia.jpg\",\"width\":1790,\"height\":1342},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/taxilamangacartagena.es\\\/index.php\\\/taxi-excursiones-cartagena\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/taxilamangacartagena.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Excursiones y Traslados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/taxilamangacartagena.es\\\/#website\",\"url\":\"https:\\\/\\\/taxilamangacartagena.es\\\/\",\"name\":\"Eurotaxi\",\"description\":\"Servicio de taxi 24 horas para tus desplazamientos por Cartagena, La Manga y la Regi\u00f3n de Murcia. Traslados al aeropuerto, veh\u00edculo adaptado para silla de ruedas y espacio para grupos y equipaje.\",\"publisher\":{\"@id\":\"https:\\\/\\\/taxilamangacartagena.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/taxilamangacartagena.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/taxilamangacartagena.es\\\/#organization\",\"name\":\"Eurotaxi\",\"url\":\"https:\\\/\\\/taxilamangacartagena.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/taxilamangacartagena.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/taxilamangacartagena.es\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/logo-eurotaxi-cartagena.png\",\"contentUrl\":\"https:\\\/\\\/taxilamangacartagena.es\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/logo-eurotaxi-cartagena.png\",\"width\":500,\"height\":167,\"caption\":\"Eurotaxi\"},\"image\":{\"@id\":\"https:\\\/\\\/taxilamangacartagena.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Excursiones y Traslados - Eurotaxi","description":"Descubre Cartagena con Eurotaxi: excursiones personalizadas y traslados c\u00f3modos. Viaja a tu ritmo y disfruta cada momento. \u00a1Reserva ahora!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/taxilamangacartagena.es\/index.php\/taxi-excursiones-cartagena\/","og_locale":"es_ES","og_type":"article","og_title":"Excursiones y Traslados - Eurotaxi","og_description":"Descubre Cartagena con Eurotaxi: excursiones personalizadas y traslados c\u00f3modos. Viaja a tu ritmo y disfruta cada momento. \u00a1Reserva ahora!","og_url":"https:\/\/taxilamangacartagena.es\/index.php\/taxi-excursiones-cartagena\/","og_site_name":"Eurotaxi","article_modified_time":"2026-08-27T22:03:29+00:00","og_image":[{"url":"https:\/\/taxilamangacartagena.es\/wp-content\/uploads\/2026\/08\/taxi-excursiones-cartagena-region-murcia.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/taxilamangacartagena.es\/index.php\/taxi-excursiones-cartagena\/","url":"https:\/\/taxilamangacartagena.es\/index.php\/taxi-excursiones-cartagena\/","name":"Excursiones y Traslados - Eurotaxi","isPartOf":{"@id":"https:\/\/taxilamangacartagena.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/taxilamangacartagena.es\/index.php\/taxi-excursiones-cartagena\/#primaryimage"},"image":{"@id":"https:\/\/taxilamangacartagena.es\/index.php\/taxi-excursiones-cartagena\/#primaryimage"},"thumbnailUrl":"https:\/\/taxilamangacartagena.es\/wp-content\/uploads\/2026\/08\/taxi-excursiones-cartagena-region-murcia.jpg","datePublished":"2026-08-27T20:23:38+00:00","dateModified":"2026-08-27T22:03:29+00:00","description":"Descubre Cartagena con Eurotaxi: excursiones personalizadas y traslados c\u00f3modos. Viaja a tu ritmo y disfruta cada momento. \u00a1Reserva ahora!","breadcrumb":{"@id":"https:\/\/taxilamangacartagena.es\/index.php\/taxi-excursiones-cartagena\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/taxilamangacartagena.es\/index.php\/taxi-excursiones-cartagena\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/taxilamangacartagena.es\/index.php\/taxi-excursiones-cartagena\/#primaryimage","url":"https:\/\/taxilamangacartagena.es\/wp-content\/uploads\/2026\/08\/taxi-excursiones-cartagena-region-murcia.jpg","contentUrl":"https:\/\/taxilamangacartagena.es\/wp-content\/uploads\/2026\/08\/taxi-excursiones-cartagena-region-murcia.jpg","width":1790,"height":1342},{"@type":"BreadcrumbList","@id":"https:\/\/taxilamangacartagena.es\/index.php\/taxi-excursiones-cartagena\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/taxilamangacartagena.es\/"},{"@type":"ListItem","position":2,"name":"Excursiones y Traslados"}]},{"@type":"WebSite","@id":"https:\/\/taxilamangacartagena.es\/#website","url":"https:\/\/taxilamangacartagena.es\/","name":"Eurotaxi","description":"Servicio de taxi 24 horas para tus desplazamientos por Cartagena, La Manga y la Regi\u00f3n de Murcia. Traslados al aeropuerto, veh\u00edculo adaptado para silla de ruedas y espacio para grupos y equipaje.","publisher":{"@id":"https:\/\/taxilamangacartagena.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/taxilamangacartagena.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/taxilamangacartagena.es\/#organization","name":"Eurotaxi","url":"https:\/\/taxilamangacartagena.es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/taxilamangacartagena.es\/#\/schema\/logo\/image\/","url":"https:\/\/taxilamangacartagena.es\/wp-content\/uploads\/2026\/08\/logo-eurotaxi-cartagena.png","contentUrl":"https:\/\/taxilamangacartagena.es\/wp-content\/uploads\/2026\/08\/logo-eurotaxi-cartagena.png","width":500,"height":167,"caption":"Eurotaxi"},"image":{"@id":"https:\/\/taxilamangacartagena.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/taxilamangacartagena.es\/index.php\/wp-json\/wp\/v2\/pages\/96","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/taxilamangacartagena.es\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/taxilamangacartagena.es\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/taxilamangacartagena.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/taxilamangacartagena.es\/index.php\/wp-json\/wp\/v2\/comments?post=96"}],"version-history":[{"count":5,"href":"https:\/\/taxilamangacartagena.es\/index.php\/wp-json\/wp\/v2\/pages\/96\/revisions"}],"predecessor-version":[{"id":199,"href":"https:\/\/taxilamangacartagena.es\/index.php\/wp-json\/wp\/v2\/pages\/96\/revisions\/199"}],"wp:attachment":[{"href":"https:\/\/taxilamangacartagena.es\/index.php\/wp-json\/wp\/v2\/media?parent=96"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}